{"id":2154,"count":11,"description":"","link":"https:\/\/engineering.jhu.edu\/magazine-archive\/topic\/computer-science\/","name":"Computer Science","slug":"computer-science","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Computer Science Archives - JHU Engineering Magazine<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Computer Science Archives - JHU Engineering Magazine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/engineering.jhu.edu\/magazine-archive\/topic\/computer-science\/\" \/>\n<meta property=\"og:site_name\" content=\"JHU Engineering Magazine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/engineering.jhu.edu\\\/magazine-archive\\\/topic\\\/computer-science\\\/\",\"url\":\"https:\\\/\\\/engineering.jhu.edu\\\/magazine-archive\\\/topic\\\/computer-science\\\/\",\"name\":\"Computer Science Archives - JHU Engineering Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/engineering.jhu.edu\\\/magazine-archive\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/engineering.jhu.edu\\\/magazine-archive\\\/topic\\\/computer-science\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/engineering.jhu.edu\\\/magazine-archive\\\/topic\\\/computer-science\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/engineering.jhu.edu\\\/magazine-archive\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Computer Science\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/engineering.jhu.edu\\\/magazine-archive\\\/#website\",\"url\":\"https:\\\/\\\/engineering.jhu.edu\\\/magazine-archive\\\/\",\"name\":\"JHU Engineering Magazine\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/engineering.jhu.edu\\\/magazine-archive\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Computer Science Archives - JHU Engineering Magazine","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Computer Science Archives - JHU Engineering Magazine","og_url":"https:\/\/engineering.jhu.edu\/magazine-archive\/topic\/computer-science\/","og_site_name":"JHU Engineering Magazine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/engineering.jhu.edu\/magazine-archive\/topic\/computer-science\/","url":"https:\/\/engineering.jhu.edu\/magazine-archive\/topic\/computer-science\/","name":"Computer Science Archives - JHU Engineering Magazine","isPartOf":{"@id":"https:\/\/engineering.jhu.edu\/magazine-archive\/#website"},"breadcrumb":{"@id":"https:\/\/engineering.jhu.edu\/magazine-archive\/topic\/computer-science\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/engineering.jhu.edu\/magazine-archive\/topic\/computer-science\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/engineering.jhu.edu\/magazine-archive\/"},{"@type":"ListItem","position":2,"name":"Computer Science"}]},{"@type":"WebSite","@id":"https:\/\/engineering.jhu.edu\/magazine-archive\/#website","url":"https:\/\/engineering.jhu.edu\/magazine-archive\/","name":"JHU Engineering Magazine","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/engineering.jhu.edu\/magazine-archive\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/engineering.jhu.edu\/magazine-archive\/wp-json\/wp\/v2\/tags\/2154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/engineering.jhu.edu\/magazine-archive\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/engineering.jhu.edu\/magazine-archive\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/engineering.jhu.edu\/magazine-archive\/wp-json\/wp\/v2\/posts?tags=2154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}